{"id":6706,"date":"2025-01-22T19:44:59","date_gmt":"2025-01-22T19:44:59","guid":{"rendered":"https:\/\/acervocarlitocarvalhosa.com.br\/?post_type=imprensa&#038;p=6706"},"modified":"2025-01-22T19:45:00","modified_gmt":"2025-01-22T19:45:00","slug":"a-jovem-transvanguarda-vai-a-bienal","status":"publish","type":"imprensa","link":"https:\/\/acervocarlitocarvalhosa.com.br\/en\/imprensa\/a-jovem-transvanguarda-vai-a-bienal\/","title":{"rendered":"A jovem transvanguarda vai \u00e0 Bienal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":6712,"template":"","meta":{"nf_dc_page":"","footnotes":""},"decada":[3],"class_list":["post-6706","imprensa","type-imprensa","status-publish","has-post-thumbnail","hentry","decada-3"],"_links":{"self":[{"href":"https:\/\/acervocarlitocarvalhosa.com.br\/en\/wp-json\/wp\/v2\/imprensa\/6706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervocarlitocarvalhosa.com.br\/en\/wp-json\/wp\/v2\/imprensa"}],"about":[{"href":"https:\/\/acervocarlitocarvalhosa.com.br\/en\/wp-json\/wp\/v2\/types\/imprensa"}],"author":[{"embeddable":true,"href":"https:\/\/acervocarlitocarvalhosa.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":2,"href":"https:\/\/acervocarlitocarvalhosa.com.br\/en\/wp-json\/wp\/v2\/imprensa\/6706\/revisions"}],"predecessor-version":[{"id":6733,"href":"https:\/\/acervocarlitocarvalhosa.com.br\/en\/wp-json\/wp\/v2\/imprensa\/6706\/revisions\/6733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervocarlitocarvalhosa.com.br\/en\/wp-json\/wp\/v2\/media\/6712"}],"wp:attachment":[{"href":"https:\/\/acervocarlitocarvalhosa.com.br\/en\/wp-json\/wp\/v2\/media?parent=6706"}],"wp:term":[{"taxonomy":"decada","embeddable":true,"href":"https:\/\/acervocarlitocarvalhosa.com.br\/en\/wp-json\/wp\/v2\/decada?post=6706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}